{"id":12535,"date":"2024-06-29T11:17:55","date_gmt":"2024-06-29T09:17:55","guid":{"rendered":"https:\/\/www.karlhauser.com\/?post_type=product&#038;p=12535"},"modified":"2025-10-17T07:56:06","modified_gmt":"2025-10-17T05:56:06","slug":"iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/de\/produkte\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\/","title":{"rendered":"III Reich Polizei Kokarde f\u00fcr den Tschako f\u00fcr Mannschaften &#8211; Hersteller Assmann &#038; S\u00f6hne L\u00fcdenscheid"},"content":{"rendered":"<p>III Reich Polizei Kokarde f\u00fcr den Tschako f\u00fcr Mannschaften &#8211; Hersteller Assmann &amp; S\u00f6hne L\u00fcdenscheid<\/p>\n<p>&nbsp;<\/p>\n<p>Size 35 x 62 mm<\/p>\n<p>Weight 24.930 gr.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>III Reich Polizei Kokarde f\u00fcr den Tschako f\u00fcr Mannschaften &#8211; Hersteller Assmann &amp; S\u00f6hne L\u00fcdenscheid<\/p>\n<p>&nbsp;<\/p>\n<p>Size 35 x 62 mm<\/p>\n<p>Weight 24.930 gr.<\/p>\n","protected":false},"featured_media":12536,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[864,383,405],"product_tag":[111,811],"class_list":["post-12535","product","type-product","status-publish","has-post-thumbnail","product_cat-cap-insigna","product_cat-german-1919-1945","product_cat-uniform-insigna","product_tag-polizei","product_tag-tschako","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>III Reich Polizei Kokarde f\u00fcr den Tschako f\u00fcr Mannschaften - Hersteller Assmann &amp; S\u00f6hne L\u00fcdenscheid - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/de\/produkte\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"III Reich Polizei Kokarde f\u00fcr den Tschako f\u00fcr Mannschaften - Hersteller Assmann &amp; S\u00f6hne L\u00fcdenscheid - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"III Reich Polizei Kokarde f\u00fcr den Tschako f\u00fcr Mannschaften - Hersteller Assmann &amp; S\u00f6hne L\u00fcdenscheid  &nbsp;  Size 35 x 62 mm  Weight 24.930 gr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/de\/produkte\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T05:56:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/06\/L1002042-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1606\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\\\/\",\"name\":\"III Reich Polizei Kokarde f\u00fcr den Tschako f\u00fcr Mannschaften - Hersteller Assmann & S\u00f6hne L\u00fcdenscheid - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/L1002042-scaled.jpg\",\"datePublished\":\"2024-06-29T09:17:55+00:00\",\"dateModified\":\"2025-10-17T05:56:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/L1002042-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/L1002042-scaled.jpg\",\"width\":2560,\"height\":1606},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"III Reich Polizei Kokarde f\u00fcr den Tschako f\u00fcr Mannschaften &#8211; Hersteller Assmann &#038; S\u00f6hne L\u00fcdenscheid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"III Reich Polizei Kokarde f\u00fcr den Tschako f\u00fcr Mannschaften - Hersteller Assmann & S\u00f6hne L\u00fcdenscheid - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/de\/produkte\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\/","og_locale":"de_DE","og_type":"article","og_title":"III Reich Polizei Kokarde f\u00fcr den Tschako f\u00fcr Mannschaften - Hersteller Assmann & S\u00f6hne L\u00fcdenscheid - Karl H\u00e4user","og_description":"III Reich Polizei Kokarde f\u00fcr den Tschako f\u00fcr Mannschaften - Hersteller Assmann &amp; S\u00f6hne L\u00fcdenscheid  &nbsp;  Size 35 x 62 mm  Weight 24.930 gr.","og_url":"https:\/\/www.karlhauser.com\/de\/produkte\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2025-10-17T05:56:06+00:00","og_image":[{"width":2560,"height":1606,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/06\/L1002042-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/de\/produkte\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\/","url":"https:\/\/www.karlhauser.com\/de\/produkte\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\/","name":"III Reich Polizei Kokarde f\u00fcr den Tschako f\u00fcr Mannschaften - Hersteller Assmann & S\u00f6hne L\u00fcdenscheid - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/de\/produkte\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/de\/produkte\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/06\/L1002042-scaled.jpg","datePublished":"2024-06-29T09:17:55+00:00","dateModified":"2025-10-17T05:56:06+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/de\/produkte\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/de\/produkte\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.karlhauser.com\/de\/produkte\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/06\/L1002042-scaled.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/06\/L1002042-scaled.jpg","width":2560,"height":1606},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/de\/produkte\/iii-reich-polizei-kokarde-fur-den-tschako-fur-mannschaften-hersteller-assmann-sohne-ludenscheid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.karlhauser.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"III Reich Polizei Kokarde f\u00fcr den Tschako f\u00fcr Mannschaften &#8211; Hersteller Assmann &#038; S\u00f6hne L\u00fcdenscheid"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/de\/#website","url":"https:\/\/www.karlhauser.com\/de\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/de\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.karlhauser.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product\/12535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/media\/12536"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/media?parent=12535"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product_brand?post=12535"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product_cat?post=12535"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product_tag?post=12535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}