{"id":14503,"date":"2024-10-11T17:53:35","date_gmt":"2024-10-11T15:53:35","guid":{"rendered":"https:\/\/www.karlhauser.com\/?post_type=product&#038;p=14503"},"modified":"2026-06-05T07:58:01","modified_gmt":"2026-06-05T05:58:01","slug":"verwundetenabzeichen-1939-in-schwarz-3","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/de\/produkte\/verwundetenabzeichen-1939-in-schwarz-3\/","title":{"rendered":"Verwundetenabzeichen 1939 in Schwarz"},"content":{"rendered":"<p>Original and untouched<\/p>\n<p>Ohne hersteller markierung<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Weight 14.160\u00a0 gr. \u2013 Size 45x 38<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":14504,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[69,401,383,940],"product_tag":[580,151],"class_list":["post-14503","product","type-product","status-publish","has-post-thumbnail","product_cat-awards","product_cat-general-decorations","product_cat-german-1919-1945","product_cat-wound-badge","product_tag-carl-wild","product_tag-verwundetenabzeichen","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verwundetenabzeichen 1939 in Schwarz - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/de\/produkte\/verwundetenabzeichen-1939-in-schwarz-3\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verwundetenabzeichen 1939 in Schwarz - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"Weight 14.160\u00a0 gr. \u2013 Size 45x 38  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/de\/produkte\/verwundetenabzeichen-1939-in-schwarz-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-05T05:58:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/10\/L1002748-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2332\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/verwundetenabzeichen-1939-in-schwarz-3\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/verwundetenabzeichen-1939-in-schwarz-3\\\/\",\"name\":\"Verwundetenabzeichen 1939 in Schwarz - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/verwundetenabzeichen-1939-in-schwarz-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/verwundetenabzeichen-1939-in-schwarz-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/L1002748-scaled.jpg\",\"datePublished\":\"2024-10-11T15:53:35+00:00\",\"dateModified\":\"2026-06-05T05:58:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/verwundetenabzeichen-1939-in-schwarz-3\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/verwundetenabzeichen-1939-in-schwarz-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/verwundetenabzeichen-1939-in-schwarz-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/L1002748-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/L1002748-scaled.jpg\",\"width\":2332,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/verwundetenabzeichen-1939-in-schwarz-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Verwundetenabzeichen 1939 in Schwarz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verwundetenabzeichen 1939 in Schwarz - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/de\/produkte\/verwundetenabzeichen-1939-in-schwarz-3\/","og_locale":"de_DE","og_type":"article","og_title":"Verwundetenabzeichen 1939 in Schwarz - Karl H\u00e4user","og_description":"Weight 14.160\u00a0 gr. \u2013 Size 45x 38  &nbsp;","og_url":"https:\/\/www.karlhauser.com\/de\/produkte\/verwundetenabzeichen-1939-in-schwarz-3\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2026-06-05T05:58:01+00:00","og_image":[{"width":2332,"height":2560,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/10\/L1002748-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/de\/produkte\/verwundetenabzeichen-1939-in-schwarz-3\/","url":"https:\/\/www.karlhauser.com\/de\/produkte\/verwundetenabzeichen-1939-in-schwarz-3\/","name":"Verwundetenabzeichen 1939 in Schwarz - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/de\/produkte\/verwundetenabzeichen-1939-in-schwarz-3\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/de\/produkte\/verwundetenabzeichen-1939-in-schwarz-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/10\/L1002748-scaled.jpg","datePublished":"2024-10-11T15:53:35+00:00","dateModified":"2026-06-05T05:58:01+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/de\/produkte\/verwundetenabzeichen-1939-in-schwarz-3\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/de\/produkte\/verwundetenabzeichen-1939-in-schwarz-3\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.karlhauser.com\/de\/produkte\/verwundetenabzeichen-1939-in-schwarz-3\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/10\/L1002748-scaled.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/10\/L1002748-scaled.jpg","width":2332,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/de\/produkte\/verwundetenabzeichen-1939-in-schwarz-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.karlhauser.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Verwundetenabzeichen 1939 in Schwarz"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/de\/#website","url":"https:\/\/www.karlhauser.com\/de\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/de\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.karlhauser.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product\/14503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/media\/14504"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/media?parent=14503"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product_brand?post=14503"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product_cat?post=14503"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product_tag?post=14503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}