{"id":8678,"date":"2024-03-04T11:01:08","date_gmt":"2024-03-04T10:01:08","guid":{"rendered":"https:\/\/www.karlhauser.com\/?post_type=product&#038;p=8678"},"modified":"2025-10-17T08:27:03","modified_gmt":"2025-10-17T06:27:03","slug":"standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/de\/produkte\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\/","title":{"rendered":"Standsch\u00fctzenverband Tirol Vorarlberg Gaumeisterabzeichen 1943 in Gold &#8211; mit Eichenlaubkranz KK Gewehr"},"content":{"rendered":"<p>Standsch\u00fctzenverband Tirol Vorarlberg Gaumeisterabzeichen 1943 in Gold &#8211; mit Eichenlaubkranz KK Gewehr<\/p>\n<p>51 mm diam<\/p>\n<p>Weight 27,770 gr.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>51 mm diam<\/p>\n<p>Weight 27,770 gr.<\/p>\n","protected":false},"featured_media":8679,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[383,375],"product_tag":[601,600],"class_list":{"0":"post-8678","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-german-1919-1945","7":"product_cat-sport-badges","8":"product_tag-standschutzenverband","9":"product_tag-tirol-vorarlberg","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Standsch\u00fctzenverband Tirol Vorarlberg Gaumeisterabzeichen 1943 in Gold - mit Eichenlaubkranz KK Gewehr - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/de\/produkte\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Standsch\u00fctzenverband Tirol Vorarlberg Gaumeisterabzeichen 1943 in Gold - mit Eichenlaubkranz KK Gewehr - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"51 mm diam  Weight 27,770 gr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/de\/produkte\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T06:27:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/03\/L1000685.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1891\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\\\/\",\"name\":\"Standsch\u00fctzenverband Tirol Vorarlberg Gaumeisterabzeichen 1943 in Gold - mit Eichenlaubkranz KK Gewehr - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/L1000685.jpg\",\"datePublished\":\"2024-03-04T10:01:08+00:00\",\"dateModified\":\"2025-10-17T06:27:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/L1000685.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/L1000685.jpg\",\"width\":1920,\"height\":1891},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/produkte\\\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Standsch\u00fctzenverband Tirol Vorarlberg Gaumeisterabzeichen 1943 in Gold &#8211; mit Eichenlaubkranz KK Gewehr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Standsch\u00fctzenverband Tirol Vorarlberg Gaumeisterabzeichen 1943 in Gold - mit Eichenlaubkranz KK Gewehr - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/de\/produkte\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\/","og_locale":"de_DE","og_type":"article","og_title":"Standsch\u00fctzenverband Tirol Vorarlberg Gaumeisterabzeichen 1943 in Gold - mit Eichenlaubkranz KK Gewehr - Karl H\u00e4user","og_description":"51 mm diam  Weight 27,770 gr.","og_url":"https:\/\/www.karlhauser.com\/de\/produkte\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2025-10-17T06:27:03+00:00","og_image":[{"width":1920,"height":1891,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/03\/L1000685.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/de\/produkte\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\/","url":"https:\/\/www.karlhauser.com\/de\/produkte\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\/","name":"Standsch\u00fctzenverband Tirol Vorarlberg Gaumeisterabzeichen 1943 in Gold - mit Eichenlaubkranz KK Gewehr - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/de\/produkte\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/de\/produkte\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/03\/L1000685.jpg","datePublished":"2024-03-04T10:01:08+00:00","dateModified":"2025-10-17T06:27:03+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/de\/produkte\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/de\/produkte\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.karlhauser.com\/de\/produkte\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/03\/L1000685.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/03\/L1000685.jpg","width":1920,"height":1891},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/de\/produkte\/standschutzenverband-tirol-vorarlberg-gaumeisterabzeichen-1943-in-gold-mit-eichenlaubkranz-kk-gewehr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.karlhauser.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Standsch\u00fctzenverband Tirol Vorarlberg Gaumeisterabzeichen 1943 in Gold &#8211; mit Eichenlaubkranz KK Gewehr"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/de\/#website","url":"https:\/\/www.karlhauser.com\/de\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/de\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.karlhauser.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product\/8678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/media\/8679"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/media?parent=8678"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product_brand?post=8678"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product_cat?post=8678"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/de\/wp-json\/wp\/v2\/product_tag?post=8678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}