{"id":10505,"date":"2024-03-27T07:41:01","date_gmt":"2024-03-27T06:41:01","guid":{"rendered":"https:\/\/www.karlhauser.com\/?post_type=product&#038;p=10505"},"modified":"2025-10-17T08:10:06","modified_gmt":"2025-10-17T06:10:06","slug":"reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/en\/products\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\/","title":{"rendered":"Reichssportabzeichen in Bronze &#8211; Urkundenheft f\u00fcr einen Mann aus Tirol"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":10509,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[69,644,383,375],"product_tag":[177,131],"class_list":{"0":"post-10505","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-awards","7":"product_cat-german-military-citations","8":"product_cat-german-1919-1945","9":"product_cat-sport-badges","10":"product_tag-sportabzeichen","11":"product_tag-tirol","13":"first","14":"outofstock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reichssportabzeichen in Bronze - Urkundenheft f\u00fcr einen Mann aus Tirol - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/en\/products\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reichssportabzeichen in Bronze - Urkundenheft f\u00fcr einen Mann aus Tirol - Karl H\u00e4user\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/en\/products\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T06:10:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/03\/L1001533.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1419\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\\\/\",\"name\":\"Reichssportabzeichen in Bronze - Urkundenheft f\u00fcr einen Mann aus Tirol - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/L1001533.jpg\",\"datePublished\":\"2024-03-27T06:41:01+00:00\",\"dateModified\":\"2025-10-17T06:10:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/L1001533.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/L1001533.jpg\",\"width\":1920,\"height\":1419},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reichssportabzeichen in Bronze &#8211; Urkundenheft f\u00fcr einen Mann aus Tirol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reichssportabzeichen in Bronze - Urkundenheft f\u00fcr einen Mann aus Tirol - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/en\/products\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\/","og_locale":"en_US","og_type":"article","og_title":"Reichssportabzeichen in Bronze - Urkundenheft f\u00fcr einen Mann aus Tirol - Karl H\u00e4user","og_url":"https:\/\/www.karlhauser.com\/en\/products\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2025-10-17T06:10:06+00:00","og_image":[{"width":1920,"height":1419,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/03\/L1001533.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/en\/products\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\/","url":"https:\/\/www.karlhauser.com\/en\/products\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\/","name":"Reichssportabzeichen in Bronze - Urkundenheft f\u00fcr einen Mann aus Tirol - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/03\/L1001533.jpg","datePublished":"2024-03-27T06:41:01+00:00","dateModified":"2025-10-17T06:10:06+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/en\/products\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.karlhauser.com\/en\/products\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/03\/L1001533.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/03\/L1001533.jpg","width":1920,"height":1419},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/en\/products\/reichssportabzeichen-in-bronze-urkundenheft-fur-einen-mann-aus-tirol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.karlhauser.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Reichssportabzeichen in Bronze &#8211; Urkundenheft f\u00fcr einen Mann aus Tirol"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/en\/#website","url":"https:\/\/www.karlhauser.com\/en\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/en\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.karlhauser.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product\/10505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/media\/10509"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/media?parent=10505"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_brand?post=10505"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_cat?post=10505"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_tag?post=10505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}