{"id":12673,"date":"2024-07-27T13:32:03","date_gmt":"2024-07-27T11:32:03","guid":{"rendered":"https:\/\/www.karlhauser.com\/?post_type=product&#038;p=12673"},"modified":"2025-10-17T07:55:04","modified_gmt":"2025-10-17T05:55:04","slug":"arbeitstag-abzeichen-1-mai-1939-third-reich","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/en\/products\/arbeitstag-abzeichen-1-mai-1939-third-reich\/","title":{"rendered":"Arbeitstag abzeichen 1 mai 1939- Third Reich"},"content":{"rendered":"<p>Arbeitstag abzeichen 1 mai 1939 &#8211; Third Reich<\/p>\n<p>Badge size 35.5 mm diam. &#8211; Weight 3.855 gr.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arbeitstag abzeichen 1 mai 1939 &#8211; Third Reich<\/p>\n<p>Badge size 35.5 mm diam. &#8211; Weight 3.855 gr.<\/p>\n","protected":false},"featured_media":12674,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[69,383,872],"product_tag":[175,120],"class_list":["post-12673","product","type-product","status-publish","has-post-thumbnail","product_cat-awards","product_cat-german-1919-1945","product_cat-tinnies","product_tag-abzeichen","product_tag-third-reich","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arbeitstag abzeichen 1 mai 1939- Third Reich - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/en\/products\/arbeitstag-abzeichen-1-mai-1939-third-reich\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arbeitstag abzeichen 1 mai 1939- Third Reich - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"Arbeitstag abzeichen 1 mai 1939 - Third Reich  Badge size 35.5 mm diam. - Weight 3.855 gr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/en\/products\/arbeitstag-abzeichen-1-mai-1939-third-reich\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T05:55:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/07\/L1002101.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2264\" \/>\n\t<meta property=\"og:image:height\" content=\"2448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/arbeitstag-abzeichen-1-mai-1939-third-reich\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/arbeitstag-abzeichen-1-mai-1939-third-reich\\\/\",\"name\":\"Arbeitstag abzeichen 1 mai 1939- Third Reich - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/arbeitstag-abzeichen-1-mai-1939-third-reich\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/arbeitstag-abzeichen-1-mai-1939-third-reich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/L1002101.jpg\",\"datePublished\":\"2024-07-27T11:32:03+00:00\",\"dateModified\":\"2025-10-17T05:55:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/arbeitstag-abzeichen-1-mai-1939-third-reich\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/arbeitstag-abzeichen-1-mai-1939-third-reich\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/arbeitstag-abzeichen-1-mai-1939-third-reich\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/L1002101.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/L1002101.jpg\",\"width\":2264,\"height\":2448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/arbeitstag-abzeichen-1-mai-1939-third-reich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arbeitstag abzeichen 1 mai 1939- Third Reich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arbeitstag abzeichen 1 mai 1939- Third Reich - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/en\/products\/arbeitstag-abzeichen-1-mai-1939-third-reich\/","og_locale":"en_US","og_type":"article","og_title":"Arbeitstag abzeichen 1 mai 1939- Third Reich - Karl H\u00e4user","og_description":"Arbeitstag abzeichen 1 mai 1939 - Third Reich  Badge size 35.5 mm diam. - Weight 3.855 gr.","og_url":"https:\/\/www.karlhauser.com\/en\/products\/arbeitstag-abzeichen-1-mai-1939-third-reich\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2025-10-17T05:55:04+00:00","og_image":[{"width":2264,"height":2448,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/07\/L1002101.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/en\/products\/arbeitstag-abzeichen-1-mai-1939-third-reich\/","url":"https:\/\/www.karlhauser.com\/en\/products\/arbeitstag-abzeichen-1-mai-1939-third-reich\/","name":"Arbeitstag abzeichen 1 mai 1939- Third Reich - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/arbeitstag-abzeichen-1-mai-1939-third-reich\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/arbeitstag-abzeichen-1-mai-1939-third-reich\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/07\/L1002101.jpg","datePublished":"2024-07-27T11:32:03+00:00","dateModified":"2025-10-17T05:55:04+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/arbeitstag-abzeichen-1-mai-1939-third-reich\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/en\/products\/arbeitstag-abzeichen-1-mai-1939-third-reich\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.karlhauser.com\/en\/products\/arbeitstag-abzeichen-1-mai-1939-third-reich\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/07\/L1002101.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2024\/07\/L1002101.jpg","width":2264,"height":2448},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/en\/products\/arbeitstag-abzeichen-1-mai-1939-third-reich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.karlhauser.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Arbeitstag abzeichen 1 mai 1939- Third Reich"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/en\/#website","url":"https:\/\/www.karlhauser.com\/en\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/en\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.karlhauser.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product\/12673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/media\/12674"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/media?parent=12673"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_brand?post=12673"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_cat?post=12673"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_tag?post=12673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}