{"id":16217,"date":"2025-01-11T09:51:41","date_gmt":"2025-01-11T08:51:41","guid":{"rendered":"https:\/\/www.karlhauser.com\/?post_type=product&#038;p=16217"},"modified":"2025-10-16T19:25:03","modified_gmt":"2025-10-16T17:25:03","slug":"wehrmacht-heer-armelabzeichen-funker-infanterie","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/en\/products\/wehrmacht-heer-armelabzeichen-funker-infanterie\/","title":{"rendered":"Wehrmacht Heer \u00c4rmelabzeichen Funker Infanterie"},"content":{"rendered":"<h1>Wehrmacht Heer \u00c4rmelabzeichen Funker Infanterie<\/h1>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<h1>Wehrmacht Heer \u00c4rmelabzeichen Funker Infanterie<\/h1>\n","protected":false},"featured_media":16224,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[858,383,405],"product_tag":[852,511,118],"class_list":["post-16217","product","type-product","status-publish","has-post-thumbnail","product_cat-arm-patches","product_cat-german-1919-1945","product_cat-uniform-insigna","product_tag-funker","product_tag-heer","product_tag-wehrmacht","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wehrmacht Heer \u00c4rmelabzeichen Funker Infanterie - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/en\/products\/wehrmacht-heer-armelabzeichen-funker-infanterie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wehrmacht Heer \u00c4rmelabzeichen Funker Infanterie - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"Wehrmacht Heer \u00c4rmelabzeichen Funker Infanterie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/en\/products\/wehrmacht-heer-armelabzeichen-funker-infanterie\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-16T17:25:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/01\/DO01003143-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1861\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/wehrmacht-heer-armelabzeichen-funker-infanterie\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/wehrmacht-heer-armelabzeichen-funker-infanterie\\\/\",\"name\":\"Wehrmacht Heer \u00c4rmelabzeichen Funker Infanterie - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/wehrmacht-heer-armelabzeichen-funker-infanterie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/wehrmacht-heer-armelabzeichen-funker-infanterie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/DO01003143-scaled.jpg\",\"datePublished\":\"2025-01-11T08:51:41+00:00\",\"dateModified\":\"2025-10-16T17:25:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/wehrmacht-heer-armelabzeichen-funker-infanterie\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/wehrmacht-heer-armelabzeichen-funker-infanterie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/wehrmacht-heer-armelabzeichen-funker-infanterie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/DO01003143-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/DO01003143-scaled.jpg\",\"width\":1861,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/wehrmacht-heer-armelabzeichen-funker-infanterie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wehrmacht Heer \u00c4rmelabzeichen Funker Infanterie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wehrmacht Heer \u00c4rmelabzeichen Funker Infanterie - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/en\/products\/wehrmacht-heer-armelabzeichen-funker-infanterie\/","og_locale":"en_US","og_type":"article","og_title":"Wehrmacht Heer \u00c4rmelabzeichen Funker Infanterie - Karl H\u00e4user","og_description":"Wehrmacht Heer \u00c4rmelabzeichen Funker Infanterie","og_url":"https:\/\/www.karlhauser.com\/en\/products\/wehrmacht-heer-armelabzeichen-funker-infanterie\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2025-10-16T17:25:03+00:00","og_image":[{"width":1861,"height":2560,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/01\/DO01003143-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/en\/products\/wehrmacht-heer-armelabzeichen-funker-infanterie\/","url":"https:\/\/www.karlhauser.com\/en\/products\/wehrmacht-heer-armelabzeichen-funker-infanterie\/","name":"Wehrmacht Heer \u00c4rmelabzeichen Funker Infanterie - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/wehrmacht-heer-armelabzeichen-funker-infanterie\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/wehrmacht-heer-armelabzeichen-funker-infanterie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/01\/DO01003143-scaled.jpg","datePublished":"2025-01-11T08:51:41+00:00","dateModified":"2025-10-16T17:25:03+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/wehrmacht-heer-armelabzeichen-funker-infanterie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/en\/products\/wehrmacht-heer-armelabzeichen-funker-infanterie\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.karlhauser.com\/en\/products\/wehrmacht-heer-armelabzeichen-funker-infanterie\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/01\/DO01003143-scaled.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/01\/DO01003143-scaled.jpg","width":1861,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/en\/products\/wehrmacht-heer-armelabzeichen-funker-infanterie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.karlhauser.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Wehrmacht Heer \u00c4rmelabzeichen Funker Infanterie"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/en\/#website","url":"https:\/\/www.karlhauser.com\/en\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/en\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.karlhauser.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product\/16217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/media\/16224"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/media?parent=16217"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_brand?post=16217"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_cat?post=16217"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_tag?post=16217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}