{"id":23491,"date":"2025-12-02T20:06:41","date_gmt":"2025-12-02T19:06:41","guid":{"rendered":"https:\/\/www.karlhauser.com\/?post_type=product&#038;p=23491"},"modified":"2026-03-26T00:17:56","modified_gmt":"2026-03-25T23:17:56","slug":"hitler-jugend-urkunde","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/en\/products\/hitler-jugend-urkunde\/","title":{"rendered":"Hitler Jugend Urkunde"},"content":{"rendered":"<p>Hitler Jugend Urkunde<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hitler Jugend Urkunde<\/p>\n","protected":false},"featured_media":23492,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[69,644,383,309],"product_tag":[147,148],"class_list":{"0":"post-23491","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-awards","7":"product_cat-german-military-citations","8":"product_cat-german-1919-1945","9":"product_cat-other-badges-decorations","10":"product_tag-drkb","11":"product_tag-veteran","13":"first","14":"outofstock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hitler Jugend Urkunde - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/en\/products\/hitler-jugend-urkunde\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hitler Jugend Urkunde - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"Hitler Jugend Urkunde\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/en\/products\/hitler-jugend-urkunde\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T23:17:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/12\/IMG-20251202-WA0017.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/hitler-jugend-urkunde\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/hitler-jugend-urkunde\\\/\",\"name\":\"Hitler Jugend Urkunde - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/hitler-jugend-urkunde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/hitler-jugend-urkunde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/IMG-20251202-WA0017.jpg\",\"datePublished\":\"2025-12-02T19:06:41+00:00\",\"dateModified\":\"2026-03-25T23:17:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/hitler-jugend-urkunde\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/hitler-jugend-urkunde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/hitler-jugend-urkunde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/IMG-20251202-WA0017.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/IMG-20251202-WA0017.jpg\",\"width\":1200,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/hitler-jugend-urkunde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hitler Jugend Urkunde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hitler Jugend Urkunde - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/en\/products\/hitler-jugend-urkunde\/","og_locale":"en_US","og_type":"article","og_title":"Hitler Jugend Urkunde - Karl H\u00e4user","og_description":"Hitler Jugend Urkunde","og_url":"https:\/\/www.karlhauser.com\/en\/products\/hitler-jugend-urkunde\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2026-03-25T23:17:56+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/12\/IMG-20251202-WA0017.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/en\/products\/hitler-jugend-urkunde\/","url":"https:\/\/www.karlhauser.com\/en\/products\/hitler-jugend-urkunde\/","name":"Hitler Jugend Urkunde - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/hitler-jugend-urkunde\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/hitler-jugend-urkunde\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/12\/IMG-20251202-WA0017.jpg","datePublished":"2025-12-02T19:06:41+00:00","dateModified":"2026-03-25T23:17:56+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/hitler-jugend-urkunde\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/en\/products\/hitler-jugend-urkunde\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.karlhauser.com\/en\/products\/hitler-jugend-urkunde\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/12\/IMG-20251202-WA0017.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/12\/IMG-20251202-WA0017.jpg","width":1200,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/en\/products\/hitler-jugend-urkunde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.karlhauser.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Hitler Jugend Urkunde"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/en\/#website","url":"https:\/\/www.karlhauser.com\/en\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/en\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.karlhauser.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product\/23491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/media\/23492"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/media?parent=23491"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_brand?post=23491"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_cat?post=23491"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_tag?post=23491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}