{"id":2582,"date":"2023-04-19T09:11:31","date_gmt":"2023-04-19T07:11:31","guid":{"rendered":"https:\/\/web.karlhauser.com\/?post_type=product&#038;p=2582"},"modified":"2025-12-14T12:20:21","modified_gmt":"2025-12-14T11:20:21","slug":"deutsche-arbeitsfront-daf-abzeichen","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/en\/products\/deutsche-arbeitsfront-daf-abzeichen\/","title":{"rendered":"Deutsche Arbeitsfront DAF &#8211; Abzeichen"},"content":{"rendered":"<p>Deutsche Arbeitsfront DAF &#8211; Abzeichen<\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">Badge size\u00a0<\/span>19 mm diameter<span style=\"font-family: Verdana; font-size: large;\">. Needle size 1 mm diameter x 50 mm legth. Weight\u00a0<\/span>2,290 gr.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-family: Verdana; font-size: large;\">Badge size\u00a0<\/span>19 mm diameter<span style=\"font-family: Verdana; font-size: large;\">. Needle size 1 mm diameter x 50 mm legth. Weight\u00a0<\/span>2,290 gr.<\/p>\n","protected":false},"featured_media":2583,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[309],"product_tag":[219,120],"class_list":["post-2582","product","type-product","status-publish","has-post-thumbnail","product_cat-other-badges-decorations","product_tag-daf","product_tag-third-reich","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deutsche Arbeitsfront DAF - Abzeichen - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/en\/products\/deutsche-arbeitsfront-daf-abzeichen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutsche Arbeitsfront DAF - Abzeichen - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"Badge size\u00a019 mm diameter. Needle size 1 mm diameter x 50 mm legth. Weight\u00a02,290 gr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/en\/products\/deutsche-arbeitsfront-daf-abzeichen\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-14T11:20:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/04\/20221222_162023-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2049\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/deutsche-arbeitsfront-daf-abzeichen\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/deutsche-arbeitsfront-daf-abzeichen\\\/\",\"name\":\"Deutsche Arbeitsfront DAF - Abzeichen - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/deutsche-arbeitsfront-daf-abzeichen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/deutsche-arbeitsfront-daf-abzeichen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/20221222_162023-scaled.jpg\",\"datePublished\":\"2023-04-19T07:11:31+00:00\",\"dateModified\":\"2025-12-14T11:20:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/deutsche-arbeitsfront-daf-abzeichen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/deutsche-arbeitsfront-daf-abzeichen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/deutsche-arbeitsfront-daf-abzeichen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/20221222_162023-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/20221222_162023-scaled.jpg\",\"width\":1920,\"height\":1537},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/deutsche-arbeitsfront-daf-abzeichen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Deutsche Arbeitsfront DAF &#8211; Abzeichen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deutsche Arbeitsfront DAF - Abzeichen - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/en\/products\/deutsche-arbeitsfront-daf-abzeichen\/","og_locale":"en_US","og_type":"article","og_title":"Deutsche Arbeitsfront DAF - Abzeichen - Karl H\u00e4user","og_description":"Badge size\u00a019 mm diameter. Needle size 1 mm diameter x 50 mm legth. Weight\u00a02,290 gr.","og_url":"https:\/\/www.karlhauser.com\/en\/products\/deutsche-arbeitsfront-daf-abzeichen\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2025-12-14T11:20:21+00:00","og_image":[{"width":2560,"height":2049,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/04\/20221222_162023-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/en\/products\/deutsche-arbeitsfront-daf-abzeichen\/","url":"https:\/\/www.karlhauser.com\/en\/products\/deutsche-arbeitsfront-daf-abzeichen\/","name":"Deutsche Arbeitsfront DAF - Abzeichen - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/deutsche-arbeitsfront-daf-abzeichen\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/deutsche-arbeitsfront-daf-abzeichen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/04\/20221222_162023-scaled.jpg","datePublished":"2023-04-19T07:11:31+00:00","dateModified":"2025-12-14T11:20:21+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/deutsche-arbeitsfront-daf-abzeichen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/en\/products\/deutsche-arbeitsfront-daf-abzeichen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.karlhauser.com\/en\/products\/deutsche-arbeitsfront-daf-abzeichen\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/04\/20221222_162023-scaled.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/04\/20221222_162023-scaled.jpg","width":1920,"height":1537},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/en\/products\/deutsche-arbeitsfront-daf-abzeichen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.karlhauser.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Deutsche Arbeitsfront DAF &#8211; Abzeichen"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/en\/#website","url":"https:\/\/www.karlhauser.com\/en\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/en\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.karlhauser.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product\/2582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/media\/2583"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/media?parent=2582"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_brand?post=2582"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_cat?post=2582"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_tag?post=2582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}