{"id":5817,"date":"2023-10-21T11:28:34","date_gmt":"2023-10-21T09:28:34","guid":{"rendered":"https:\/\/www.karlhauser.com\/?post_type=product&#038;p=5817"},"modified":"2023-10-21T11:28:35","modified_gmt":"2023-10-21T09:28:35","slug":"infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/en\/products\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\/","title":{"rendered":"Infanteriesturmabzeichen in silber &#8211; Hersteller  Adolf Scholze"},"content":{"rendered":"<p>Infanteriesturmabzeichen in silber &#8211; Hersteller Adolf Scholze<\/p>\n<p>Infantry Assault Badge<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Weight 32, 74 gr.<\/p>\n<p>Size 48 mm x 63 mm x 4 mm<\/p>\n","protected":false},"featured_media":5818,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[306],"product_tag":[133,118],"class_list":{"0":"post-5817","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-badges","7":"product_tag-infanterie","8":"product_tag-wehrmacht","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Infanteriesturmabzeichen in silber - Hersteller Adolf Scholze - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/en\/products\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infanteriesturmabzeichen in silber - Hersteller Adolf Scholze - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"Weight 32, 74 gr.  Size 48 mm x 63 mm x 4 mm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/en\/products\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-21T09:28:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/10\/IMG_6813.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1784\" \/>\n\t<meta property=\"og:image:height\" content=\"2232\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\\\/\",\"name\":\"Infanteriesturmabzeichen in silber - Hersteller Adolf Scholze - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IMG_6813.jpg\",\"datePublished\":\"2023-10-21T09:28:34+00:00\",\"dateModified\":\"2023-10-21T09:28:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IMG_6813.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IMG_6813.jpg\",\"width\":1784,\"height\":2232},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/products\\\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Infanteriesturmabzeichen in silber &#8211; Hersteller Adolf Scholze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Infanteriesturmabzeichen in silber - Hersteller Adolf Scholze - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/en\/products\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\/","og_locale":"en_US","og_type":"article","og_title":"Infanteriesturmabzeichen in silber - Hersteller Adolf Scholze - Karl H\u00e4user","og_description":"Weight 32, 74 gr.  Size 48 mm x 63 mm x 4 mm","og_url":"https:\/\/www.karlhauser.com\/en\/products\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2023-10-21T09:28:35+00:00","og_image":[{"width":1784,"height":2232,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/10\/IMG_6813.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/en\/products\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\/","url":"https:\/\/www.karlhauser.com\/en\/products\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\/","name":"Infanteriesturmabzeichen in silber - Hersteller Adolf Scholze - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/10\/IMG_6813.jpg","datePublished":"2023-10-21T09:28:34+00:00","dateModified":"2023-10-21T09:28:35+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/en\/products\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/en\/products\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.karlhauser.com\/en\/products\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/10\/IMG_6813.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/10\/IMG_6813.jpg","width":1784,"height":2232},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/en\/products\/infanteriesturmabzeichen-in-silber-hersteller-adolf-scholze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.karlhauser.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Infanteriesturmabzeichen in silber &#8211; Hersteller Adolf Scholze"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/en\/#website","url":"https:\/\/www.karlhauser.com\/en\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/en\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.karlhauser.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product\/5817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/media\/5818"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/media?parent=5817"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_brand?post=5817"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_cat?post=5817"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/en\/wp-json\/wp\/v2\/product_tag?post=5817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}