{"id":19781,"date":"2025-07-14T18:17:18","date_gmt":"2025-07-14T16:17:18","guid":{"rendered":"https:\/\/www.karlhauser.com\/?post_type=product&#038;p=19781"},"modified":"2026-07-15T17:58:48","modified_gmt":"2026-07-15T15:58:48","slug":"wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/it\/prodotti\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\/","title":{"rendered":"Wehrmacht Heer Paar Kragenspiegel f\u00fcr einen Zahlmeister"},"content":{"rendered":"<p>Wehrmacht Heer Paar Kragenspiegel f\u00fcr einen Zahlmeister<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wehrmacht Heer Paar Kragenspiegel f\u00fcr einen Zahlmeister<\/p>\n","protected":false},"featured_media":19782,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[914,383,961,405],"product_tag":[133,611],"class_list":["post-19781","product","type-product","status-publish","has-post-thumbnail","product_cat-collar-tabs","product_cat-german-1919-1945","product_cat-heer-collar-tabs","product_cat-uniform-insigna","product_tag-infanterie","product_tag-kragenspiegel","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wehrmacht Heer Paar Kragenspiegel f\u00fcr einen Zahlmeister - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/it\/prodotti\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wehrmacht Heer Paar Kragenspiegel f\u00fcr einen Zahlmeister - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"Wehrmacht Heer Paar Kragenspiegel f\u00fcr einen Zahlmeister\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/it\/prodotti\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T15:58:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/07\/IMG-20250711-WA0029.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\\\/\",\"name\":\"Wehrmacht Heer Paar Kragenspiegel f\u00fcr einen Zahlmeister - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/IMG-20250711-WA0029.jpg\",\"datePublished\":\"2025-07-14T16:17:18+00:00\",\"dateModified\":\"2026-07-15T15:58:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/IMG-20250711-WA0029.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/IMG-20250711-WA0029.jpg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wehrmacht Heer Paar Kragenspiegel f\u00fcr einen Zahlmeister\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wehrmacht Heer Paar Kragenspiegel f\u00fcr einen Zahlmeister - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/it\/prodotti\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\/","og_locale":"it_IT","og_type":"article","og_title":"Wehrmacht Heer Paar Kragenspiegel f\u00fcr einen Zahlmeister - Karl H\u00e4user","og_description":"Wehrmacht Heer Paar Kragenspiegel f\u00fcr einen Zahlmeister","og_url":"https:\/\/www.karlhauser.com\/it\/prodotti\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2026-07-15T15:58:48+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/07\/IMG-20250711-WA0029.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\/","url":"https:\/\/www.karlhauser.com\/it\/prodotti\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\/","name":"Wehrmacht Heer Paar Kragenspiegel f\u00fcr einen Zahlmeister - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/07\/IMG-20250711-WA0029.jpg","datePublished":"2025-07-14T16:17:18+00:00","dateModified":"2026-07-15T15:58:48+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/it\/prodotti\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/07\/IMG-20250711-WA0029.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/07\/IMG-20250711-WA0029.jpg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/wehrmacht-heer-paar-kragenspiegel-fur-einen-zahlmeister\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/www.karlhauser.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Wehrmacht Heer Paar Kragenspiegel f\u00fcr einen Zahlmeister"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/it\/#website","url":"https:\/\/www.karlhauser.com\/it\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/it\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.karlhauser.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product\/19781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/media\/19782"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/media?parent=19781"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_brand?post=19781"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_cat?post=19781"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_tag?post=19781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}