{"id":2059,"date":"2023-04-15T11:10:23","date_gmt":"2023-04-15T09:10:23","guid":{"rendered":"https:\/\/web.karlhauser.com\/?post_type=product&#038;p=2059"},"modified":"2026-06-18T12:26:37","modified_gmt":"2026-06-18T10:26:37","slug":"deutscher-luftsportverband-abzeichen-aluminium-bernstein","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/it\/prodotti\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\/","title":{"rendered":"Deutscher Luftsportverband Abzeichen &#8211; Aluminium &#8211; Bernstein"},"content":{"rendered":"<p>Deutscher Luftsportverband Abzeichen &#8211; Aluminium &#8211; Bernstein<\/p>\n<p>Badge Size 30 mm diameter<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Badge Size 30 mm diameter<\/p>\n<p>Weight 1.305 gr.<\/p>\n","protected":false},"featured_media":2060,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[309],"product_tag":[175,137],"class_list":["post-2059","product","type-product","status-publish","has-post-thumbnail","product_cat-other-badges-decorations","product_tag-abzeichen","product_tag-luftsport","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deutscher Luftsportverband Abzeichen - Aluminium - Bernstein - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/it\/prodotti\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutscher Luftsportverband Abzeichen - Aluminium - Bernstein - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"Badge Size 30 mm diameter  Weight 1.305 gr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/it\/prodotti\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-18T10:26:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/04\/IMG_4461.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1572\" \/>\n\t<meta property=\"og:image:height\" content=\"1254\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\\\/\",\"name\":\"Deutscher Luftsportverband Abzeichen - Aluminium - Bernstein - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IMG_4461.jpg\",\"datePublished\":\"2023-04-15T09:10:23+00:00\",\"dateModified\":\"2026-06-18T10:26:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IMG_4461.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IMG_4461.jpg\",\"width\":1572,\"height\":1254},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Deutscher Luftsportverband Abzeichen &#8211; Aluminium &#8211; Bernstein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deutscher Luftsportverband Abzeichen - Aluminium - Bernstein - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/it\/prodotti\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\/","og_locale":"it_IT","og_type":"article","og_title":"Deutscher Luftsportverband Abzeichen - Aluminium - Bernstein - Karl H\u00e4user","og_description":"Badge Size 30 mm diameter  Weight 1.305 gr.","og_url":"https:\/\/www.karlhauser.com\/it\/prodotti\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2026-06-18T10:26:37+00:00","og_image":[{"width":1572,"height":1254,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/04\/IMG_4461.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\/","url":"https:\/\/www.karlhauser.com\/it\/prodotti\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\/","name":"Deutscher Luftsportverband Abzeichen - Aluminium - Bernstein - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/04\/IMG_4461.jpg","datePublished":"2023-04-15T09:10:23+00:00","dateModified":"2026-06-18T10:26:37+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/it\/prodotti\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/04\/IMG_4461.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2023\/04\/IMG_4461.jpg","width":1572,"height":1254},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/deutscher-luftsportverband-abzeichen-aluminium-bernstein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/www.karlhauser.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Deutscher Luftsportverband Abzeichen &#8211; Aluminium &#8211; Bernstein"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/it\/#website","url":"https:\/\/www.karlhauser.com\/it\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/it\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.karlhauser.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product\/2059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/media\/2060"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/media?parent=2059"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_brand?post=2059"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_cat?post=2059"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_tag?post=2059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}