{"id":22344,"date":"2025-11-22T21:44:28","date_gmt":"2025-11-22T20:44:28","guid":{"rendered":"https:\/\/www.karlhauser.com\/?post_type=product&#038;p=22344"},"modified":"2025-11-22T21:47:37","modified_gmt":"2025-11-22T20:47:37","slug":"sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/it\/prodotti\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\/","title":{"rendered":"SA-Sportabzeichen Modell ab 1939 in Bronze &#8211; Hersteller Fechler Bernsbach"},"content":{"rendered":"<p>SA-Sportabzeichen Modell ab 1939 in Bronze<\/p>\n<p>Hersteller Fechler Bernsbach<\/p>\n<p>Weight 17.810 gr.<\/p>\n<p>Size 47 x 59mm<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hersteller Fechler Bernsbach<\/p>\n<p>Weight 17.810 gr.<\/p>\n<p>Size 47 x 59mm<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":22360,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[69,383,375],"product_tag":[293,177],"class_list":{"0":"post-22344","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-awards","7":"product_cat-german-1919-1945","8":"product_cat-sport-badges","9":"product_tag-sa","10":"product_tag-sportabzeichen","12":"first","13":"outofstock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SA-Sportabzeichen Modell ab 1939 in Bronze - Hersteller Fechler Bernsbach - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/it\/prodotti\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SA-Sportabzeichen Modell ab 1939 in Bronze - Hersteller Fechler Bernsbach - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"Hersteller Fechler Bernsbach  Weight 17.810 gr.  Size 47 x 59mm  &nbsp;  &nbsp;  &nbsp;  &nbsp;  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/it\/prodotti\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-22T20:47:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/11\/IMG-20251122-WA0106.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\\\/\",\"name\":\"SA-Sportabzeichen Modell ab 1939 in Bronze - Hersteller Fechler Bernsbach - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG-20251122-WA0106.jpg\",\"datePublished\":\"2025-11-22T20:44:28+00:00\",\"dateModified\":\"2025-11-22T20:47:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG-20251122-WA0106.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG-20251122-WA0106.jpg\",\"width\":2000,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SA-Sportabzeichen Modell ab 1939 in Bronze &#8211; Hersteller Fechler Bernsbach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SA-Sportabzeichen Modell ab 1939 in Bronze - Hersteller Fechler Bernsbach - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/it\/prodotti\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\/","og_locale":"it_IT","og_type":"article","og_title":"SA-Sportabzeichen Modell ab 1939 in Bronze - Hersteller Fechler Bernsbach - Karl H\u00e4user","og_description":"Hersteller Fechler Bernsbach  Weight 17.810 gr.  Size 47 x 59mm  &nbsp;  &nbsp;  &nbsp;  &nbsp;  &nbsp;","og_url":"https:\/\/www.karlhauser.com\/it\/prodotti\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2025-11-22T20:47:37+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/11\/IMG-20251122-WA0106.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\/","url":"https:\/\/www.karlhauser.com\/it\/prodotti\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\/","name":"SA-Sportabzeichen Modell ab 1939 in Bronze - Hersteller Fechler Bernsbach - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/11\/IMG-20251122-WA0106.jpg","datePublished":"2025-11-22T20:44:28+00:00","dateModified":"2025-11-22T20:47:37+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/it\/prodotti\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/11\/IMG-20251122-WA0106.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/11\/IMG-20251122-WA0106.jpg","width":2000,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/sa-sportabzeichen-modell-ab-1939-in-bronze-hersteller-fechler-bernsbach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/www.karlhauser.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"SA-Sportabzeichen Modell ab 1939 in Bronze &#8211; Hersteller Fechler Bernsbach"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/it\/#website","url":"https:\/\/www.karlhauser.com\/it\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/it\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.karlhauser.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product\/22344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/media\/22360"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/media?parent=22344"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_brand?post=22344"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_cat?post=22344"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_tag?post=22344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}