{"id":22833,"date":"2025-11-27T11:40:05","date_gmt":"2025-11-27T10:40:05","guid":{"rendered":"https:\/\/www.karlhauser.com\/?post_type=product&#038;p=22833"},"modified":"2025-11-27T11:41:16","modified_gmt":"2025-11-27T10:41:16","slug":"luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/it\/prodotti\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\/","title":{"rendered":"Luftwaffe Paar Schulterklappen f\u00fcr  einen Unteroffizieranw\u00e4rter der Fliegertruppe"},"content":{"rendered":"<p>Luftwaffe Paar Schulterklappen f\u00fcr einen Unteroffizieranw\u00e4rter der Fliegertruppe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luftwaffe Paar Schulterklappen f\u00fcr einen Unteroffizieranw\u00e4rter der Fliegertruppe<\/p>\n","protected":false},"featured_media":22834,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[383,855,405],"product_tag":[854,118],"class_list":["post-22833","product","type-product","status-publish","has-post-thumbnail","product_cat-german-1919-1945","product_cat-shoulder-boards","product_cat-uniform-insigna","product_tag-schulterklappen","product_tag-wehrmacht","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luftwaffe Paar Schulterklappen f\u00fcr einen Unteroffizieranw\u00e4rter der Fliegertruppe - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/it\/prodotti\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luftwaffe Paar Schulterklappen f\u00fcr einen Unteroffizieranw\u00e4rter der Fliegertruppe - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"Luftwaffe Paar Schulterklappen f\u00fcr einen Unteroffizieranw\u00e4rter der Fliegertruppe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/it\/prodotti\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-27T10:41:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/11\/IMG-20251127-WA0007-rotated.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\\\/\",\"name\":\"Luftwaffe Paar Schulterklappen f\u00fcr einen Unteroffizieranw\u00e4rter der Fliegertruppe - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG-20251127-WA0007-rotated.jpg\",\"datePublished\":\"2025-11-27T10:40:05+00:00\",\"dateModified\":\"2025-11-27T10:41:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG-20251127-WA0007-rotated.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG-20251127-WA0007-rotated.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luftwaffe Paar Schulterklappen f\u00fcr einen Unteroffizieranw\u00e4rter der Fliegertruppe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luftwaffe Paar Schulterklappen f\u00fcr einen Unteroffizieranw\u00e4rter der Fliegertruppe - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/it\/prodotti\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\/","og_locale":"it_IT","og_type":"article","og_title":"Luftwaffe Paar Schulterklappen f\u00fcr einen Unteroffizieranw\u00e4rter der Fliegertruppe - Karl H\u00e4user","og_description":"Luftwaffe Paar Schulterklappen f\u00fcr einen Unteroffizieranw\u00e4rter der Fliegertruppe","og_url":"https:\/\/www.karlhauser.com\/it\/prodotti\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2025-11-27T10:41:16+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/11\/IMG-20251127-WA0007-rotated.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\/","url":"https:\/\/www.karlhauser.com\/it\/prodotti\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\/","name":"Luftwaffe Paar Schulterklappen f\u00fcr einen Unteroffizieranw\u00e4rter der Fliegertruppe - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/11\/IMG-20251127-WA0007-rotated.jpg","datePublished":"2025-11-27T10:40:05+00:00","dateModified":"2025-11-27T10:41:16+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/it\/prodotti\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/11\/IMG-20251127-WA0007-rotated.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2025\/11\/IMG-20251127-WA0007-rotated.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/luftwaffe-paar-schulterklappen-fur-einen-unteroffizieranwarter-der-fliegertruppe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/www.karlhauser.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Luftwaffe Paar Schulterklappen f\u00fcr einen Unteroffizieranw\u00e4rter der Fliegertruppe"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/it\/#website","url":"https:\/\/www.karlhauser.com\/it\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/it\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.karlhauser.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product\/22833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/media\/22834"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/media?parent=22833"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_brand?post=22833"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_cat?post=22833"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_tag?post=22833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}