{"id":25115,"date":"2026-03-22T14:09:02","date_gmt":"2026-03-22T13:09:02","guid":{"rendered":"https:\/\/www.karlhauser.com\/?post_type=product&#038;p=25115"},"modified":"2026-06-05T08:22:13","modified_gmt":"2026-06-05T06:22:13","slug":"eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/it\/prodotti\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\/","title":{"rendered":"EISERNES KREUZ 1939  2 KLASSE &#8211; Arbeitsgemeinschaft der Graveur Gold und Silberschemiede Innungen"},"content":{"rendered":"<p>EISERNES KREUZ 1939 2 KLASSE &#8211; Arbeitsgemeinschaft der Graveur Gold und Silberschemiede Innungen<\/p>\n<p>&nbsp;<\/p>\n<p>Size 44.5 x 44.5 &#8211; Weight 19.900 gr.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WITH ITS ORIGINAL RIBBON<\/p>\n","protected":false},"featured_media":25117,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[69,401,383,943],"product_tag":[349,332,354],"class_list":["post-25115","product","type-product","status-publish","has-post-thumbnail","product_cat-awards","product_cat-general-decorations","product_cat-german-1919-1945","product_cat-iron-cross","product_tag-349","product_tag-iron-cross","product_tag-karl-hauser","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EISERNES KREUZ 1939 2 KLASSE - Arbeitsgemeinschaft der Graveur Gold und Silberschemiede Innungen - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/it\/prodotti\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EISERNES KREUZ 1939 2 KLASSE - Arbeitsgemeinschaft der Graveur Gold und Silberschemiede Innungen - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"WITH ITS ORIGINAL RIBBON\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/it\/prodotti\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-05T06:22:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2026\/03\/20260322_141205.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\\\/\",\"name\":\"EISERNES KREUZ 1939 2 KLASSE - Arbeitsgemeinschaft der Graveur Gold und Silberschemiede Innungen - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260322_141205.jpg\",\"datePublished\":\"2026-03-22T13:09:02+00:00\",\"dateModified\":\"2026-06-05T06:22:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260322_141205.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260322_141205.jpg\",\"width\":1920,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EISERNES KREUZ 1939 2 KLASSE &#8211; Arbeitsgemeinschaft der Graveur Gold und Silberschemiede Innungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EISERNES KREUZ 1939 2 KLASSE - Arbeitsgemeinschaft der Graveur Gold und Silberschemiede Innungen - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/it\/prodotti\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\/","og_locale":"it_IT","og_type":"article","og_title":"EISERNES KREUZ 1939 2 KLASSE - Arbeitsgemeinschaft der Graveur Gold und Silberschemiede Innungen - Karl H\u00e4user","og_description":"WITH ITS ORIGINAL RIBBON","og_url":"https:\/\/www.karlhauser.com\/it\/prodotti\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2026-06-05T06:22:13+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2026\/03\/20260322_141205.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\/","url":"https:\/\/www.karlhauser.com\/it\/prodotti\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\/","name":"EISERNES KREUZ 1939 2 KLASSE - Arbeitsgemeinschaft der Graveur Gold und Silberschemiede Innungen - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2026\/03\/20260322_141205.jpg","datePublished":"2026-03-22T13:09:02+00:00","dateModified":"2026-06-05T06:22:13+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/it\/prodotti\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2026\/03\/20260322_141205.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2026\/03\/20260322_141205.jpg","width":1920,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/eisernes-kreuz-1939-2-klasse-arbeitsgemeinschaft-der-graveur-gold-und-silberschemiede-innungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/www.karlhauser.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"EISERNES KREUZ 1939 2 KLASSE &#8211; Arbeitsgemeinschaft der Graveur Gold und Silberschemiede Innungen"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/it\/#website","url":"https:\/\/www.karlhauser.com\/it\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/it\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.karlhauser.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product\/25115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/media\/25117"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/media?parent=25115"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_brand?post=25115"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_cat?post=25115"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_tag?post=25115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}