{"id":26213,"date":"2026-05-28T16:56:26","date_gmt":"2026-05-28T14:56:26","guid":{"rendered":"https:\/\/www.karlhauser.com\/?post_type=product&#038;p=26213"},"modified":"2026-06-05T07:51:27","modified_gmt":"2026-06-05T05:51:27","slug":"verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2","status":"publish","type":"product","link":"https:\/\/www.karlhauser.com\/it\/prodotti\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\/","title":{"rendered":"Verwundetenabzeichen 1939 in Silber Hersteller 30 &#8211; Hauptm\u00fcnzamt Wien"},"content":{"rendered":"<p>Weight 27.110 gr.<\/p>\n<p>Size 36.4\u00a0 x 43.8 mm<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Weight 33.535 gr.<\/p>\n<p>Size 36.4\u00a0 x 43.8 mm<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":26214,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[69,401,383,940],"product_tag":[511,151],"class_list":["post-26213","product","type-product","status-publish","has-post-thumbnail","product_cat-awards","product_cat-general-decorations","product_cat-german-1919-1945","product_cat-wound-badge","product_tag-heer","product_tag-verwundetenabzeichen","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verwundetenabzeichen 1939 in Silber Hersteller 30 - Hauptm\u00fcnzamt Wien - Karl H\u00e4user<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.karlhauser.com\/it\/prodotti\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verwundetenabzeichen 1939 in Silber Hersteller 30 - Hauptm\u00fcnzamt Wien - Karl H\u00e4user\" \/>\n<meta property=\"og:description\" content=\"Weight 33.535 gr.  Size 36.4\u00a0 x 43.8 mm  &nbsp;  &nbsp;  &nbsp;  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.karlhauser.com\/it\/prodotti\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Karl H\u00e4user\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-05T05:51:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2026\/05\/20260528_164506.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\\\/\",\"name\":\"Verwundetenabzeichen 1939 in Silber Hersteller 30 - Hauptm\u00fcnzamt Wien - Karl H\u00e4user\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/20260528_164506.jpg\",\"datePublished\":\"2026-05-28T14:56:26+00:00\",\"dateModified\":\"2026-06-05T05:51:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/20260528_164506.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/20260528_164506.jpg\",\"width\":1920,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/prodotti\\\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Verwundetenabzeichen 1939 in Silber Hersteller 30 &#8211; Hauptm\u00fcnzamt Wien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\",\"name\":\"Karl H\u00e4user\",\"description\":\"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#organization\",\"name\":\"Karl H\u00e4user\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.karlhauser.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/KH-generico-3.jpg\",\"width\":470,\"height\":470,\"caption\":\"Karl H\u00e4user\"},\"image\":{\"@id\":\"https:\\\/\\\/www.karlhauser.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/karlhauser.antik\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt-9t2bku12mwXmte0FJLGQ\",\"https:\\\/\\\/www.ebay.it\\\/str\\\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verwundetenabzeichen 1939 in Silber Hersteller 30 - Hauptm\u00fcnzamt Wien - Karl H\u00e4user","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.karlhauser.com\/it\/prodotti\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\/","og_locale":"it_IT","og_type":"article","og_title":"Verwundetenabzeichen 1939 in Silber Hersteller 30 - Hauptm\u00fcnzamt Wien - Karl H\u00e4user","og_description":"Weight 33.535 gr.  Size 36.4\u00a0 x 43.8 mm  &nbsp;  &nbsp;  &nbsp;  &nbsp;","og_url":"https:\/\/www.karlhauser.com\/it\/prodotti\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\/","og_site_name":"Karl H\u00e4user","article_modified_time":"2026-06-05T05:51:27+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2026\/05\/20260528_164506.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\/","url":"https:\/\/www.karlhauser.com\/it\/prodotti\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\/","name":"Verwundetenabzeichen 1939 in Silber Hersteller 30 - Hauptm\u00fcnzamt Wien - Karl H\u00e4user","isPartOf":{"@id":"https:\/\/www.karlhauser.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\/#primaryimage"},"image":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2026\/05\/20260528_164506.jpg","datePublished":"2026-05-28T14:56:26+00:00","dateModified":"2026-06-05T05:51:27+00:00","breadcrumb":{"@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.karlhauser.com\/it\/prodotti\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\/#primaryimage","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2026\/05\/20260528_164506.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2026\/05\/20260528_164506.jpg","width":1920,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.karlhauser.com\/it\/prodotti\/verwundetenabzeichen-1939-in-silber-hersteller-30-hauptmunzamt-wien-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.karlhauser.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/www.karlhauser.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Verwundetenabzeichen 1939 in Silber Hersteller 30 &#8211; Hauptm\u00fcnzamt Wien"}]},{"@type":"WebSite","@id":"https:\/\/www.karlhauser.com\/it\/#website","url":"https:\/\/www.karlhauser.com\/it\/","name":"Karl H\u00e4user","description":"Milit\u00e4rische Antiquit\u00e4ten und Waffen Vermittlung","publisher":{"@id":"https:\/\/www.karlhauser.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.karlhauser.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.karlhauser.com\/it\/#organization","name":"Karl H\u00e4user","url":"https:\/\/www.karlhauser.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.karlhauser.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","contentUrl":"https:\/\/www.karlhauser.com\/wp-content\/uploads\/2022\/09\/KH-generico-3.jpg","width":470,"height":470,"caption":"Karl H\u00e4user"},"image":{"@id":"https:\/\/www.karlhauser.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/karlhauser.antik\/","https:\/\/www.youtube.com\/channel\/UCt-9t2bku12mwXmte0FJLGQ","https:\/\/www.ebay.it\/str\/karlhausermilitaryantiques?_trksid=p2047675.m3561.l2563"]}]}},"_links":{"self":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product\/26213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/media\/26214"}],"wp:attachment":[{"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/media?parent=26213"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_brand?post=26213"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_cat?post=26213"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.karlhauser.com\/it\/wp-json\/wp\/v2\/product_tag?post=26213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}